{"id":8173,"date":"2023-10-20T07:41:16","date_gmt":"2023-10-20T07:41:16","guid":{"rendered":"https:\/\/www.nogometnionline.com\/?post_type=product&#038;p=8173"},"modified":"2023-10-20T07:41:17","modified_gmt":"2023-10-20T07:41:17","slug":"moski-nogometni-dresi-atletico-madrid-tretji-2023-24-kratek-rokav-tisk-antoine-griezmann-7","status":"publish","type":"product","link":"https:\/\/www.nogometnizaotroke.com\/it\/product\/moski-nogometni-dresi-atletico-madrid-tretji-2023-24-kratek-rokav-tisk-antoine-griezmann-7\/","title":{"rendered":"Maglie Calcio Uomo Atletico Madrid Terzo 2023-24 Manica Corta Stampa Antoine Griezmann 7"},"content":{"rendered":"<p>Suggerimenti per i calzini: la maglietta non include i calzini per impostazione predefinita. Se si desiderano i calzini, selezionare le opzioni relative ai calzini per pagarli.<\/p>\n<p>Suggerimento per la stampa: se il nome e il numero nell'immagine sono esattamente quelli desiderati, non \u00e8 necessario inserirli di nuovo. In caso contrario, inserire il nome e il numero desiderati.<\/p>\n<p>Consiglio per il lavaggio: si consiglia di lavare le maglie da calcio a mano. Se si desidera utilizzare una lavatrice, ricordarsi di girare la maglia e poi lavarla. Riempire la macchina con acqua fredda e utilizzare un ciclo di lavaggio delicato per proteggere maggiormente i colori.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nasveti za nogavice: Majica ne vsebuje nogavic privzeto. \u010ce \u017eelite nogavice, izberite mo\u017enosti nogavic, da jih pla\u010date. Nasveti za tiskom: \u010ce sta ime in \u0161tevilka na sliki natanko to, kar \u017eelite, vam tega ni treba ve\u010d vna\u0161ati. \u010ce ni, potem vnesite \u017eeleno ime in \u0161tevilko. Nasveti za pranje: Priporo\u010dljivo je, da nogometni dresi operete ro\u010dno. [&hellip;]<\/p>","protected":false},"featured_media":8175,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[140,41],"product_tag":[622,150,514,513,621,148,193,147],"class_list":{"0":"post-8173","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-moski","7":"product_cat-nogometni-dresi-atletico-madrid","8":"product_tag-dres-antoine-griezmann-za-otroke","9":"product_tag-moski-nogometni-dresi","10":"product_tag-nogometni-dresi-atletico-madrid-prodaja","11":"product_tag-nogometni-dresi-atletico-madrid-z-lastnim-tiskom","12":"product_tag-otroski-dresi-antoine-griezmann","13":"product_tag-poceni-nogometni-dresi","14":"product_tag-poceni-nogometni-dresi-atletico-madrid-z-lastnim-imenom-online","15":"product_tag-slovenski-nogometni-dresi","17":"first","18":"instock","19":"shipping-taxable","20":"purchasable","21":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product\/8173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/comments?post=8173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/media\/8175"}],"wp:attachment":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/media?parent=8173"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product_brand?post=8173"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product_cat?post=8173"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product_tag?post=8173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}