{"id":15396,"date":"2024-08-08T11:54:12","date_gmt":"2024-08-08T11:54:12","guid":{"rendered":"https:\/\/www.nogometnionline.com\/?post_type=product&#038;p=15396"},"modified":"2024-08-08T11:54:17","modified_gmt":"2024-08-08T11:54:17","slug":"nakup-otroski-nogometni-dresi-kompleti-za-otroke-everton-domaci-2024-25","status":"publish","type":"product","link":"https:\/\/www.nogometnizaotroke.com\/it\/product\/nakup-otroski-nogometni-dresi-kompleti-za-otroke-everton-domaci-2024-25\/","title":{"rendered":"Acquista maglie da calcio per bambini Kit per bambini Everton Home 2024-25"},"content":{"rendered":"<p>Suggerimenti per i calzini: la maglietta non include i calzini per impostazione predefinita. Se si desiderano i calzini, selezionare le opzioni relative ai calzini per pagarli.<\/p>\n<p>Suggerimento per la stampa: se il nome e il numero nell'immagine sono esattamente quelli desiderati, non \u00e8 necessario inserirli di nuovo. In caso contrario, inserire il nome e il numero desiderati.<\/p>\n<p>Consiglio per il lavaggio: si consiglia di lavare le maglie da calcio a mano. Se si desidera utilizzare una lavatrice, ricordarsi di girare la maglia e poi lavarla. Riempire la macchina con acqua fredda e utilizzare un ciclo di lavaggio delicato per proteggere maggiormente i colori.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nasveti za nogavice: Majica ne vsebuje nogavic privzeto. \u010ce \u017eelite nogavice, izberite mo\u017enosti nogavic, da jih pla\u010date. Nasveti za tiskom: \u010ce sta ime in \u0161tevilka na sliki natanko to, kar \u017eelite, vam tega ni treba ve\u010d vna\u0161ati. \u010ce ni, potem vnesite \u017eeleno ime in \u0161tevilko. Nasveti za pranje: Priporo\u010dljivo je, da nogometni dresi operete ro\u010dno. [&hellip;]<\/p>","protected":false},"featured_media":15398,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[73,49],"product_tag":[1101,153,220,1102,159,1100,148,774,147],"class_list":{"0":"post-15396","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-otroski","7":"product_cat-nogometni-dresi-everton","8":"product_tag-dresi-everton-za-otroke","9":"product_tag-nogometni-dresi","10":"product_tag-nogometni-dresi-za-otroke","11":"product_tag-otroski-dresi-everton-z-lastnim-imenom","12":"product_tag-otroski-nogometni-dresi","13":"product_tag-otroski-nogometni-dresi-everton","14":"product_tag-poceni-nogometni-dresi","15":"product_tag-poceni-otroski-nogometni-dresi-everton-z-lastnim-imenom","16":"product_tag-slovenski-nogometni-dresi","18":"first","19":"instock","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product\/15396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/comments?post=15396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/media\/15398"}],"wp:attachment":[{"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/media?parent=15396"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product_brand?post=15396"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product_cat?post=15396"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.nogometnizaotroke.com\/it\/wp-json\/wp\/v2\/product_tag?post=15396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}